{"id":21943,"date":"2022-12-23T10:05:00","date_gmt":"2022-12-23T09:05:00","guid":{"rendered":"https:\/\/opificiodellepietredure.cultura.gov.it\/persone\/ricciardi-luciano\/"},"modified":"2022-12-23T10:05:00","modified_gmt":"2022-12-23T09:05:00","slug":"ricciardi-luciano","status":"publish","type":"persone","link":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/","title":{"rendered":"Ricciardi Luciano"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":9763,"template":"","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false},"area":[661,670,759],"insegnamenti":[],"class_list":["post-21943","persone","type-persone","status-publish","has-post-thumbnail","hentry","area-restoration-department-canvas-and-panel-paintings","area-restoration-departments","area-wooden-support","profili-professionali-conservative-restoration-officer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ricciardi Luciano - Opificio Pietre Dure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricciardi Luciano - Opificio Pietre Dure\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/\" \/>\n<meta property=\"og:site_name\" content=\"Opificio Pietre Dure\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/\",\"name\":\"Ricciardi Luciano - Opificio Pietre Dure\",\"isPartOf\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg\",\"datePublished\":\"2022-12-23T09:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#primaryimage\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg\",\"contentUrl\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Persone\",\"item\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricciardi Luciano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/\",\"name\":\"Opificio Pietre Dure\",\"description\":\"L&#039;Opificio delle Pietre Dure\",\"publisher\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization\",\"name\":\"Opificio Pietre Dure\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png\",\"contentUrl\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png\",\"width\":605,\"height\":204,\"caption\":\"Opificio Pietre Dure\"},\"image\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricciardi Luciano - Opificio Pietre Dure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/","og_locale":"en_US","og_type":"article","og_title":"Ricciardi Luciano - Opificio Pietre Dure","og_url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/","og_site_name":"Opificio Pietre Dure","og_image":[{"width":500,"height":500,"url":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/","name":"Ricciardi Luciano - Opificio Pietre Dure","isPartOf":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#primaryimage"},"image":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#primaryimage"},"thumbnailUrl":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg","datePublished":"2022-12-23T09:05:00+00:00","breadcrumb":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#primaryimage","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg","contentUrl":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/RICCIARDI-Luciano.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/ricciardi-luciano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Persone","item":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/"},{"@type":"ListItem","position":2,"name":"Ricciardi Luciano"}]},{"@type":"WebSite","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/","name":"Opificio Pietre Dure","description":"L&#039;Opificio delle Pietre Dure","publisher":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization","name":"Opificio Pietre Dure","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png","contentUrl":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png","width":605,"height":204,"caption":"Opificio Pietre Dure"},"image":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/persone\/21943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/persone"}],"about":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/types\/persone"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/media\/9763"}],"wp:attachment":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/media?parent=21943"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/area?post=21943"},{"taxonomy":"insegnamenti","embeddable":true,"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/insegnamenti?post=21943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}