{"id":21894,"date":"2022-12-23T10:04:59","date_gmt":"2022-12-23T09:04:59","guid":{"rendered":"https:\/\/opificiodellepietredure.cultura.gov.it\/persone\/lanfranchi-maria-rosa\/"},"modified":"2022-12-23T10:04:59","modified_gmt":"2022-12-23T09:04:59","slug":"lanfranchi-maria-rosa","status":"publish","type":"persone","link":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/","title":{"rendered":"Lanfranchi Maria Rosa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":15215,"template":"","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false},"area":[668,670],"insegnamenti":[],"class_list":["post-21894","persone","type-persone","status-publish","has-post-thumbnail","hentry","area-restoration-department-mural-paintings-and-stucco-decorations","area-restoration-departments","profili-professionali-conservative-restoration-officer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lanfranchi Maria Rosa - Opificio Pietre Dure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lanfranchi Maria Rosa - Opificio Pietre Dure\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Opificio Pietre Dure\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"613\" \/>\n\t<meta property=\"og:image:height\" content=\"632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/\",\"name\":\"Lanfranchi Maria Rosa - Opificio Pietre Dure\",\"isPartOf\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg\",\"datePublished\":\"2022-12-23T09:04:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#primaryimage\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg\",\"contentUrl\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg\",\"width\":613,\"height\":632},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Persone\",\"item\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lanfranchi Maria Rosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/\",\"name\":\"Opificio Pietre Dure\",\"description\":\"L&#039;Opificio delle Pietre Dure\",\"publisher\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization\",\"name\":\"Opificio Pietre Dure\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png\",\"contentUrl\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png\",\"width\":605,\"height\":204,\"caption\":\"Opificio Pietre Dure\"},\"image\":{\"@id\":\"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lanfranchi Maria Rosa - Opificio Pietre Dure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/","og_locale":"en_US","og_type":"article","og_title":"Lanfranchi Maria Rosa - Opificio Pietre Dure","og_url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/","og_site_name":"Opificio Pietre Dure","og_image":[{"width":613,"height":632,"url":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/","name":"Lanfranchi Maria Rosa - Opificio Pietre Dure","isPartOf":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#primaryimage"},"image":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#primaryimage"},"thumbnailUrl":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg","datePublished":"2022-12-23T09:04:59+00:00","breadcrumb":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#primaryimage","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg","contentUrl":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/Lanfranchi-Maria-Rosa.jpg","width":613,"height":632},{"@type":"BreadcrumbList","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/lanfranchi-maria-rosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Persone","item":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/persone\/"},{"@type":"ListItem","position":2,"name":"Lanfranchi Maria Rosa"}]},{"@type":"WebSite","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#website","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/","name":"Opificio Pietre Dure","description":"L&#039;Opificio delle Pietre Dure","publisher":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#organization","name":"Opificio Pietre Dure","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png","contentUrl":"https:\/\/opificiodellepietredure.cultura.gov.it\/wp-content\/uploads\/2022\/12\/opificio-delle-pietre-dure-logo-1.png","width":605,"height":204,"caption":"Opificio Pietre Dure"},"image":{"@id":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/persone\/21894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/persone"}],"about":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/types\/persone"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/media\/15215"}],"wp:attachment":[{"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/media?parent=21894"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/area?post=21894"},{"taxonomy":"insegnamenti","embeddable":true,"href":"https:\/\/opificiodellepietredure.cultura.gov.it\/en\/wp-json\/wp\/v2\/insegnamenti?post=21894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}